{"id":3571,"date":"2026-02-07T20:45:45","date_gmt":"2026-02-07T19:45:45","guid":{"rendered":"https:\/\/infini.phytoquant.mc\/blog\/?p=3571"},"modified":"2026-05-07T11:46:46","modified_gmt":"2026-05-07T09:46:46","slug":"programmer-la-sante","status":"publish","type":"post","link":"https:\/\/phytoquant.mc\/blog\/programmer-la-sante\/","title":{"rendered":"Programmez votre sant\u00e9 : quand les mots deviennent m\u00e9decine"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3571\" class=\"elementor elementor-3571\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56c5e8d e-flex e-con-boxed e-con e-parent\" data-id=\"56c5e8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-739febc5 e-con-full e-flex e-con e-child\" data-id=\"739febc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-20ca76b e-con-full e-flex e-con e-child\" data-id=\"20ca76b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52ccb9e elementor-widget elementor-widget-heading\" data-id=\"52ccb9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/phytoquant.mc\/blog\">Blog<\/a><\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e16a2d5 elementor-widget elementor-widget-image\" data-id=\"e16a2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"9\" height=\"15\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Vector9.svg\" class=\"attachment-full size-full wp-image-452\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9578e3f elementor-widget elementor-widget-heading\" data-id=\"9578e3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><span>Notre Phytosophie<\/span><\/p>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb57426 e-con-full e-flex e-con e-child\" data-id=\"eb57426\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5acf11 elementor-widget elementor-widget-image\" data-id=\"c5acf11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"9\" height=\"15\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Vector9.svg\" class=\"attachment-full size-full wp-image-452\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-623eb4f elementor-widget elementor-widget-heading\" data-id=\"623eb4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Programmez votre sant\u00e9 : quand les mots deviennent m\u00e9decine<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29c11834 e-con-full e-flex e-con e-child\" data-id=\"29c11834\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9aa9975 e-con-full e-flex e-con e-child\" data-id=\"9aa9975\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5da1d15d elementor-widget elementor-widget-heading\" data-id=\"5da1d15d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Conseils sant\u00e9 &amp; bien-\u00eatre<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-631f317c elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"631f317c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Programmez votre sant\u00e9 : quand les mots deviennent m\u00e9decine<\/h1>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d0506cd e-con-full e-flex e-con e-child\" data-id=\"4d0506cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3207726a e-con-full e-flex e-con e-child\" data-id=\"3207726a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46109dfd elementor-widget elementor-widget-heading\" data-id=\"46109dfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Publi\u00e9 le<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eefa51c elementor-widget elementor-widget-heading\" data-id=\"eefa51c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">7 f\u00e9vrier 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64431a89 e-con-full e-flex e-con e-child\" data-id=\"64431a89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5df4635b elementor-widget elementor-widget-heading\" data-id=\"5df4635b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Mis \u00e0 jour le:<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75eb5454 elementor-widget elementor-widget-heading\" data-id=\"75eb5454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">7 f\u00e9vrier 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55e57879 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"55e57879\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-161c21e elementor-widget elementor-widget-heading\" data-id=\"161c21e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Lecture :<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69049572 elementor-widget elementor-widget-heading\" data-id=\"69049572\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">4 min<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3c0a18 elementor-widget elementor-widget-image\" data-id=\"d3c0a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1064\" height=\"550\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/mind-1.png\" class=\"attachment-full size-full wp-image-3574\" alt=\"Article PhytoQuant Programmez votre sant\u00e9 quand les mots deviennent m\u00e9decine\u200b\" srcset=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/mind-1.png 1064w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/mind-1-300x155.png 300w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/mind-1-1024x529.png 1024w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/mind-1-768x397.png 768w\" sizes=\"(max-width: 1064px) 100vw, 1064px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-114e2f22 e-con-full e-flex e-con e-child\" data-id=\"114e2f22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4b4ff88d e-con-full e-flex e-con e-child\" data-id=\"4b4ff88d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2c607411 e-con-full e-flex e-con e-child\" data-id=\"2c607411\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f941735 elementor-position-left elementor-position-left elementor-vertical-align-middle elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"4f941735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"40\" height=\"40\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/11\/PhytoQuant-autors-avatars.png\" class=\"attachment-full size-full wp-image-2452\" alt=\"nicola-frassanito-fondateur-phytoquant-monaco\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Auteur<\/h3><p class=\"elementor-image-box-description\">Nicola Frassanito<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ecdd410 e-con-full e-flex e-con e-child\" data-id=\"3ecdd410\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:30,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t<div class=\"elementor-element elementor-element-305733b7 e-con-full e-flex e-con e-child\" data-id=\"305733b7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-214a5aea elementor-widget elementor-widget-heading\" data-id=\"214a5aea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Dans cet article :<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14d0a181 elementor-widget elementor-widget-table-of-contents\" data-id=\"14d0a181\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;exclude_headings_by_selector&quot;:[],&quot;no_headings_message&quot;:&quot;No found on this page.&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-toc__14d0a181\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39310732 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"39310732\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-69d453b e-con-full e-flex e-con e-child\" data-id=\"69d453b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-126af0d9 elementor-widget elementor-widget-image\" data-id=\"126af0d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/company\/phytoquant\/posts\/?feedView=all\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link.svg\" class=\"attachment-full size-full wp-image-192\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bbdc84c elementor-widget elementor-widget-image\" data-id=\"7bbdc84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link1.svg\" class=\"attachment-full size-full wp-image-193\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-daaffa elementor-widget elementor-widget-image\" data-id=\"daaffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link2.svg\" class=\"attachment-full size-full wp-image-194\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bc5894f elementor-widget elementor-widget-image\" data-id=\"2bc5894f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCIiorNVHXGUIvcqX1YxX2AQ\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link3.svg\" class=\"attachment-full size-full wp-image-195\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-198c163c e-con-full post_right e-flex e-con e-child\" data-id=\"198c163c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-53a95c28 e-con-full e-flex e-con e-child\" data-id=\"53a95c28\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-677c8c5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"677c8c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Avez-vous remarqu\u00e9 \u00e0 quel point notre vocabulaire quotidien est satur\u00e9 du mot \u00ab maladie \u00bb ? Assurance maladie, cong\u00e9 maladie, syst\u00e8me de sant\u00e9 qui parle surtout de\u2026 maladie. Et si ce simple choix de mots orientait inconsciemment notre r\u00e9alit\u00e9 ?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ff91c2d e-con-full e-flex e-con e-child\" data-id=\"1ff91c2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c643867 elementor-widget elementor-widget-heading\" data-id=\"6c643867\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c0 retenir<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76882a0c elementor-widget__width-initial elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"76882a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><rect x=\"1\" y=\"1\" width=\"18\" height=\"18\" rx=\"9\" fill=\"#849163\"><\/rect><path d=\"M14 6L8.26087 14L6 11.7391\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Les mots que nous utilisons programment notre inconscient et influencent notre \u00e9tat de sant\u00e9.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><rect x=\"1\" y=\"1\" width=\"18\" height=\"18\" rx=\"9\" fill=\"#849163\"><\/rect><path d=\"M14 6L8.26087 14L6 11.7391\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Remplacer le langage de la \u00ab maladie \u00bb par celui de la \u00ab sant\u00e9 \u00bb r\u00e9oriente le mental positivement.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><rect x=\"1\" y=\"1\" width=\"18\" height=\"18\" rx=\"9\" fill=\"#849163\"><\/rect><path d=\"M14 6L8.26087 14L6 11.7391\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Une nutrition moderne optimis\u00e9e, soutenue par des compl\u00e9ments cibl\u00e9s, renforce l\u2019organisme.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><rect x=\"1\" y=\"1\" width=\"18\" height=\"18\" rx=\"9\" fill=\"#849163\"><\/rect><path d=\"M14 6L8.26087 14L6 11.7391\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le rire et la joie de vivre agissent comme de puissants r\u00e9gulateurs physiologiques.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><rect x=\"1\" y=\"1\" width=\"18\" height=\"18\" rx=\"9\" fill=\"#849163\"><\/rect><path d=\"M14 6L8.26087 14L6 11.7391\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sant\u00e9 mentale, corps nourri et \u00e9motions positives forment une synergie pr\u00e9ventive essentielle.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-377692e4 e-con-full e-flex e-con e-child\" data-id=\"377692e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0b32e6 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"a0b32e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le pouvoir insoup\u00e7onn\u00e9 des mots\n<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f9cc4c9 e-con-full e-flex e-con e-child\" data-id=\"2f9cc4c9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7515b8a0 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"7515b8a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"172\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Words.png\" class=\"attachment-full size-full wp-image-3575\" alt=\"\" srcset=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Words.png 305w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Words-300x169.png 300w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4861ee55 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4861ee55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Notre inconscient fonctionne comme un serviteur ultra-performant : il cherche constamment \u00e0 valider ce que notre conscience lui r\u00e9p\u00e8te. Lorsque nous parlons sans cesse de \u00ab maladie \u00bb, nous programmons litt\u00e9ralement notre esprit \u00e0 reconna\u00eetre, anticiper et m\u00eame manifester cet \u00e9tat. <\/span><b>C\u2019est un m\u00e9canisme de confirmation automatique<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a1026cf e-con-full e-flex e-con e-child\" data-id=\"3a1026cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa4c4c6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2fa4c4c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Imaginez l\u2019inverse : et si nous parlions syst\u00e9matiquement de \u00ab sant\u00e9 \u00bb ? \u00ab Mon assurance sant\u00e9 \u00bb, \u00ab mon capital sant\u00e9 \u00bb, \u00ab renforcer ma sant\u00e9 \u00bb. Ce changement linguistique peut sembler cosm\u00e9tique, mais il r\u00e9oriente fondamentalement notre focus mental. <\/span><b>L\u2019inconscient, recevant ces nouveaux messages, se met alors \u00e0 chercher des moyens de valider cette r\u00e9alit\u00e9 positive<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\">Les mots ne sont pas neutres. Ils sculptent nos pens\u00e9es, qui fa\u00e7onnent nos \u00e9motions, qui influencent nos actions, qui d\u00e9terminent nos r\u00e9sultats.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39eab98f elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"39eab98f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nourrir son corps, compl\u00e9ter intelligemment\n<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3008445e e-con-full e-flex e-con e-child\" data-id=\"3008445e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29b548b elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"29b548b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"172\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Nourish-your-body.png\" class=\"attachment-full size-full wp-image-3576\" alt=\"Nourrir son corps, compl\u00e9ter intelligemment\" srcset=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Nourish-your-body.png 305w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Nourish-your-body-300x169.png 300w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a305dba elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4a305dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Parall\u00e8lement \u00e0 cette reprogrammation mentale, notre corps reste une machine biologique qui n\u00e9cessite des nutriments de qualit\u00e9. Parlons franchement : notre alimentation moderne, m\u00eame avec les meilleures intentions, pr\u00e9sente des carences. Sols appauvris, transformation industrielle, rythme de vie effr\u00e9n\u00e9 qui nous pousse vers la facilit\u00e9 plut\u00f4t que la qualit\u00e9.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27145ccc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"27145ccc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">C\u2019est l\u00e0 qu\u2019intervient une approche pragmatique : les compl\u00e9ments alimentaires ne sont pas un aveu d\u2019\u00e9chec, mais un ajustement intelligent face \u00e0 notre r\u00e9alit\u00e9. Vitamines, min\u00e9raux, <a href=\"https:\/\/phytoquant.mc\/acides-gras\/737-quantaomega3-fort.html\" target=\"_blank\" rel=\"noopener\">om\u00e9ga-3<\/a>, probiotiques\u2026 autant d\u2019alli\u00e9s pour combler les vides nutritionnels et donner \u00e0 notre organisme les outils dont il a besoin pour maintenir cet \u00e9tat de sant\u00e9 que nous cultivons d\u00e9sormais avec nos mots.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6819d069 e-con-full e-flex e-con e-child\" data-id=\"6819d069\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bbdb547 elementor-widget__width-inherit elementor-widget elementor-widget-shortcode\" data-id=\"1bbdb547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"ps-slider-container ps-style-modern\"><div class=\"swiper ps-slider-6a988ae4879c2\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"ps-product-card\"><div class=\"ps-product-image\"><img decoding=\"async\" src=\"https:\/\/phytoquant.mc\/api\/images\/products\/737\/3178?ws_key=CVAQBISZR39FZWSREPHECLEYB7NMV7DD\" alt=\"QuantaOmega3 Fort\"><\/div><div class=\"ps-product-info\"><h3 class=\"ps-product-name\">QuantaOmega3 Fort<\/h3><div class=\"ps-product-description\"><p align=\"justify\">Omega3 de poisson bleu : C\u0153ur, cerveau, vision, femmes enceintes.<\/p><\/div><div class=\"ps-product-price\">36,00 \u20ac<\/div><a href=\"https:\/\/phytoquant.mc\/index.php?controller=product&#038;id_product=737\" class=\"ps-product-button\" target=\"_blank\">Voir le produit<\/a><\/div><\/div><\/div><\/div><div class=\"swiper-pagination\"><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div><script>\n        document.addEventListener(\"DOMContentLoaded\", function() {\n            new Swiper(\".ps-slider-6a988ae4879c2\", {\n                slidesPerView: 1,\n                spaceBetween: 20,\n                autoplay: { delay: 3000 },\n                pagination: { el: \".swiper-pagination\", clickable: true },\n                navigation: { nextEl: \".swiper-button-next\", prevEl: \".swiper-button-prev\" },\n                breakpoints: {\n                    768: { slidesPerView: 1 },\n                    1024: { slidesPerView: 1 }\n                }\n            });\n        });\n        <\/script><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ef6ebb elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"77ef6ebb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ma touche personnelle : rire et c\u00e9l\u00e9brer la vie\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fef2c08 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5fef2c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Mais voici ce que j\u2019ajoute \u00e0 cette \u00e9quation, et c\u2019est peut-\u00eatre l\u2019ingr\u00e9dient le plus puissant : rire et \u00eatre heureux de vivre.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43d4b188 e-con-full e-flex e-con e-child\" data-id=\"43d4b188\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7233356a elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"7233356a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"305\" height=\"172\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Happy-.png\" class=\"attachment-full size-full wp-image-3577\" alt=\"Ma touche personnelle : rire et c\u00e9l\u00e9brer la vie\" srcset=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Happy-.png 305w, https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2026\/02\/Happy--300x169.png 300w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30f0aac0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"30f0aac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le rire n\u2019est pas qu\u2019une \u00e9motion agr\u00e9able. C\u2019est un m\u00e9dicament gratuit, sans effets secondaires, qui lib\u00e8re des endorphines, r\u00e9duit le cortisol, renforce le syst\u00e8me immunitaire et cr\u00e9e un \u00e9tat physiologique incompatible avec le stress chronique. \u00catre heureux de vivre, c\u2019est entretenir une gratitude active qui nourrit notre \u00e9nergie vitale.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-409002e0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"409002e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Observez les personnes qui rayonnent de sant\u00e9 : elles ont souvent ce rapport l\u00e9ger, joyeux \u00e0 l\u2019existence. Ce n\u2019est pas un hasard.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b5786fb elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"4b5786fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre invitation \u00e0 agir<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-653eb6ba elementor-widget elementor-widget-text-editor\" data-id=\"653eb6ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Je vous propose donc cette philosophie int\u00e9gr\u00e9e :<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Changez votre vocabulaire : traquez le mot \u00ab maladie \u00bb dans vos conversations et remplacez-le par \u201csant\u00e9\u201d. Observez comment ce simple ajustement transforme vos pens\u00e9es.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Nourrissez-vous intelligemment : mangez le mieux possible et compl\u00e9tez sans culpabilit\u00e9 ce que l\u2019alimentation moderne ne peut plus offrir pleinement.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Riez, souriez, vibrez : cherchez activement ce qui vous fait du bien, ce qui vous fait rire, ce qui vous rappelle que vivre est un cadeau extraordinaire.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Votre inconscient vous \u00e9coute. Votre corps vous r\u00e9pond. Votre vie vous refl\u00e8te.<\/span><\/p><p><b>Alors, qu\u2019allez-vous lui dire aujourd\u2019hui ?<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-174b364c e-con-full e-flex e-con e-child\" data-id=\"174b364c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5339ab98 e-con-full e-flex e-con e-child\" data-id=\"5339ab98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-314868fd e-con-full e-flex e-con e-child\" data-id=\"314868fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce3dc86 elementor-position-left elementor-position-left elementor-vertical-align-middle elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"ce3dc86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"40\" height=\"40\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/11\/PhytoQuant-autors-avatars.png\" class=\"attachment-full size-full wp-image-2452\" alt=\"nicola-frassanito-fondateur-phytoquant-monaco\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Nicola Frassanito<\/h3><p class=\"elementor-image-box-description\">Fondateur et CEO chez PhytoQuant<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33f900c1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"33f900c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nicola Frassanito, fondateur et PDG de PhytoQuant, expert passionn\u00e9 en herboristerie. Cr\u00e9ateur de la marque de compl\u00e9ments alimentaires Phyto Quant en 2004, il conjugue sa passion pour les plantes \u00e0 son omgagement pour la sant\u00e9 naturelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-202a7548 e-con-full e-flex e-con e-child\" data-id=\"202a7548\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7ad65a elementor-widget elementor-widget-image\" data-id=\"7c7ad65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/company\/phytoquant\/posts\/?feedView=all\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link.svg\" class=\"attachment-full size-full wp-image-192\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bdf2f58 elementor-widget elementor-widget-image\" data-id=\"1bdf2f58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link1.svg\" class=\"attachment-full size-full wp-image-193\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53871c42 elementor-widget elementor-widget-image\" data-id=\"53871c42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link2.svg\" class=\"attachment-full size-full wp-image-194\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a5140b6 elementor-widget elementor-widget-image\" data-id=\"6a5140b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCIiorNVHXGUIvcqX1YxX2AQ\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link3.svg\" class=\"attachment-full size-full wp-image-195\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d266350 e-con-full e-flex e-con e-child\" data-id=\"5d266350\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d6f7a7 elementor-widget elementor-widget-heading\" data-id=\"1d6f7a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Questions fr\u00e9quentes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5adab239 elementor-widget elementor-widget-n-accordion\" data-id=\"5adab239\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1520\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1520\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Que signifie programmer la sant\u00e9 ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M23.5 12H0.5\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g clip-path=\"url(#clip0_2131_10399)\"><path d=\"M12 1V23\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M23 12H1\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2131_10399\"><rect width=\"24\" height=\"24\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1520\" class=\"elementor-element elementor-element-e0b9527 e-con-full e-flex e-con e-child\" data-id=\"e0b9527\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5095c933 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5095c933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"160\" data-end=\"464\">Programmer la sant\u00e9 consiste \u00e0 orienter consciemment ses pens\u00e9es, ses mots et ses habitudes vers la sant\u00e9 plut\u00f4t que vers la maladie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1521\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1521\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Les mots peuvent-ils vraiment influencer la sant\u00e9 ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M23.5 12H0.5\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g clip-path=\"url(#clip0_2131_10399)\"><path d=\"M12 1V23\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M23 12H1\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2131_10399\"><rect width=\"24\" height=\"24\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1521\" class=\"elementor-element elementor-element-d58cd84 e-con-full e-flex e-con e-child\" data-id=\"d58cd84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5b0913 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6e5b0913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"471\" data-end=\"764\">Oui, les mots influencent l\u2019inconscient, qui impacte les \u00e9motions, les comportements et donc l\u2019\u00e9tat de sant\u00e9 global.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1522\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1522\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Comment programmer la sant\u00e9 au quotidien ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M23.5 12H0.5\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g clip-path=\"url(#clip0_2131_10399)\"><path d=\"M12 1V23\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M23 12H1\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2131_10399\"><rect width=\"24\" height=\"24\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1522\" class=\"elementor-element elementor-element-7eded724 e-con-full e-flex e-con e-child\" data-id=\"7eded724\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-733ad62c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"733ad62c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"771\" data-end=\"1063\">Pour programmer la sant\u00e9, il faut adopter un vocabulaire positif, une alimentation adapt\u00e9e et des routines favorables au bien-\u00eatre.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1523\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1523\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> La nutrition joue-t-elle un r\u00f4le dans le fait de programmer la sant\u00e9 ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M23.5 12H0.5\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g clip-path=\"url(#clip0_2131_10399)\"><path d=\"M12 1V23\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M23 12H1\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2131_10399\"><rect width=\"24\" height=\"24\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1523\" class=\"elementor-element elementor-element-1fb2124b e-con-full e-flex e-con e-child\" data-id=\"1fb2124b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1677ff elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3a1677ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1070\" data-end=\"1384\">Absolument, une nutrition \u00e9quilibr\u00e9e et des compl\u00e9ments cibl\u00e9s soutiennent le corps dans cette d\u00e9marche de programmation sant\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1524\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1524\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Le mental et les \u00e9motions influencent-ils la sant\u00e9 physique ? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M23.5 12H0.5\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\"><g clip-path=\"url(#clip0_2131_10399)\"><path d=\"M12 1V23\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M23 12H1\" stroke=\"#202020\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_2131_10399\"><rect width=\"24\" height=\"24\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1524\" class=\"elementor-element elementor-element-2a4778f8 e-con-full e-flex e-con e-child\" data-id=\"2a4778f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48c14e2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"48c14e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1391\" data-end=\"1664\">Oui, le mental et les \u00e9motions influencent directement le stress, l\u2019immunit\u00e9 et l\u2019\u00e9quilibre physiologique.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-671cfbcb e-con-full e-flex e-con e-child\" data-id=\"671cfbcb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-11137c86 e-con-full e-flex e-con e-child\" data-id=\"11137c86\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2e620cc3 e-con-full e-flex e-con e-child\" data-id=\"2e620cc3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-103fbae0 elementor-widget elementor-widget-heading\" data-id=\"103fbae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Publi\u00e9 le<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a1b5f7f elementor-widget elementor-widget-heading\" data-id=\"7a1b5f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">7 f\u00e9vrier 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73cb4c3f e-con-full e-flex e-con e-child\" data-id=\"73cb4c3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76911b04 elementor-widget elementor-widget-heading\" data-id=\"76911b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Mis \u00e0 jour le:<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467d6ace elementor-widget elementor-widget-heading\" data-id=\"467d6ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">7 f\u00e9vrier 2026<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4aad2b7f e-con-full e-flex e-con e-child\" data-id=\"4aad2b7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65172788 elementor-widget elementor-widget-image\" data-id=\"65172788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/company\/phytoquant\/posts\/?feedView=all\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link.svg\" class=\"attachment-full size-full wp-image-192\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f67f8c9 elementor-widget elementor-widget-image\" data-id=\"6f67f8c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link1.svg\" class=\"attachment-full size-full wp-image-193\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f74247e elementor-widget elementor-widget-image\" data-id=\"2f74247e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/phytoquant\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link2.svg\" class=\"attachment-full size-full wp-image-194\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f330ac1 elementor-widget elementor-widget-image\" data-id=\"7f330ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCIiorNVHXGUIvcqX1YxX2AQ\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"35\" height=\"35\" src=\"https:\/\/phytoquant.mc\/blog\/wp-content\/uploads\/2025\/10\/Social-Link3.svg\" class=\"attachment-full size-full wp-image-195\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Blog Conseils sant\u00e9 &amp; bien-\u00eatre Programmez votre sant\u00e9 : quand les mots deviennent m\u00e9decine Publi\u00e9 le 7 f\u00e9vrier 2026 Mis \u00e0 jour le: 7 f\u00e9vrier 2026 Lecture : 4 min Auteur Nicola Frassanito Dans cet article : Avez-vous remarqu\u00e9 \u00e0 quel point notre vocabulaire quotidien est satur\u00e9 du mot \u00ab maladie \u00bb ? Assurance maladie, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[49],"tags":[],"blog-health-categories":[21],"class_list":["post-3571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevention-sante","blog-health-categories-notre-phytosophie"],"acf":[],"_links":{"self":[{"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/posts\/3571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/comments?post=3571"}],"version-history":[{"count":17,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/posts\/3571\/revisions"}],"predecessor-version":[{"id":5742,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/posts\/3571\/revisions\/5742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/media\/3581"}],"wp:attachment":[{"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/media?parent=3571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/categories?post=3571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/tags?post=3571"},{"taxonomy":"blog-health-categories","embeddable":true,"href":"https:\/\/phytoquant.mc\/blog\/wp-json\/wp\/v2\/blog-health-categories?post=3571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}